{"id":198,"count":4,"description":"Der Airbus A321-200 ist einer der meistgeflogenen Schmalrumpfjets auf Kurz- und Mittelstrecken weltweit \u2013 und trotz seiner kompakten Gr\u00f6\u00dfe bieten einige Airlines auf diesem Typ bemerkenswert hochwertige Business Class Produkte. Auf dieser Seite sind alle A321-200 Trip Reports von miles-around gesammelt \u2013 mit klarem Fokus auf Business Class Reviews.\r\n\r\nVertreten sind die Turkish Airlines Business Class im Airbus A321 auf dem Kurzstreckenflug von Berlin nach Istanbul als Anschluss an die Langstrecke nach Kuala Lumpur, die Aegean Airlines Business Class im Airbus A321-200 von Berlin nach Athen sowie die British Airways Long Haul Business Class im Airbus A321 von San Francisco nach Oslo \u2013 ein besonderer Vertreter, da British Airways auf dieser Strecke eine echte Liegeflat-Konfiguration auf einem Kurzstreckenflugzeug betreibt. Die Berichte richten sich an Vielflieger, die wissen m\u00f6chten, welche Airline das beste Business Class Produkt im A321-200 bietet.","link":"https:\/\/www.miles-around.de\/fr\/tag\/a321-200\/","name":"A321-200","slug":"a321-200","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.miles-around.de\/fr\/wp-json\/wp\/v2\/tags\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.miles-around.de\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.miles-around.de\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.miles-around.de\/fr\/wp-json\/wp\/v2\/posts?tags=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}